{"id":1776,"date":"2018-01-09T16:49:41","date_gmt":"2018-01-09T15:49:41","guid":{"rendered":"http:\/\/www.mibhydro.com\/?page_id=1776"},"modified":"2021-06-02T17:21:04","modified_gmt":"2021-06-02T15:21:04","slug":"presse-a-compression-de-smc","status":"publish","type":"page","link":"https:\/\/www.mibhydro.com\/en\/compression-a-chaud\/presse-a-compression-de-smc\/","title":{"rendered":"S.M.C. COMPRESSION PRESS"},"content":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row&#8221; enable_overlay=&#8221;enable_overlay_value&#8221; overlay_color=&#8221;rgba(255,255,255,0.82)&#8221; seperator_enable=&#8221;seperator_enable_value&#8221; seperator_type=&#8221;tilt_left_seperator&#8221; seperator_svg_height=&#8221;60&#8243; seperator_shape_background=&#8221;#e74c4a&#8221;][vc_column width=&#8221;1\/2&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-6053\" class=\"aio-icon-box left-icon\" style=\"\"  ><div class=\"aio-icon-left\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon advanced \"  style=\"color:#dd3333;border-style:solid;border-color:#dd3333;border-width:1px;width:80px;height:80px;line-height:80px;border-radius:500px;font-size:50px;display:inline-block;\">\n\t<i class=\"Defaults-angle-right\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-ibd-block\"><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-6053 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"desktop:27px;\",\"line-height\":\"\"}'  style=\"color:#e10318;\">S.M.C. COMPRESSION PRESS<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-6053 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">COMPOSITE BOARDING<\/div> <!-- description --><\/div> <!-- aio-ibd-block --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[vc_separator color=&#8221;custom&#8221; align=&#8221;align_left&#8221; border_width=&#8221;2&#8243; accent_color=&#8221;#c9c9c9&#8243; css=&#8221;.vc_custom_1510151129236{margin-top: -25px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1519381682229{margin-top: 40px !important;}&#8221;]<strong>Big SMC composite parts requires presses platens\u00a0which have to be wide and long. Press\u2019 frame\u00a0must be strong enough to avoid any deflection during\u00a0the force uprising to guarantee the straightness\u00a0of the parts. Synchronized cylinders allows\u00a0the perfect parallelism between both platens during\u00a0the mould closing.<\/strong><\/p>\n<p>Compression presses supply pressure and heating\u00a0of the SMC to be manufacture. Compression press\u00a0allows a pressure setting fitting the parts need. Pressure holding is adjustable as well regarding\u00a0the mould process without any hydraulic oil overheating\u00a0by using of variable flow pumps.\u00a0Mould heat is not conducted to press frame by\u00a0using of insulating platens.<br \/>\nSize of big SMC parts requires automatic loading\u00a0and unloading by robot. The cell composed by\u00a0this press, robot and fence is a proper automatic\u00a0line which allows a very good production rate.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;1569&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; bg_type=&#8221;bg_color&#8221; bg_override=&#8221;full&#8221; seperator_enable=&#8221;seperator_enable_value&#8221; seperator_type=&#8221;tilt_right_seperator&#8221; seperator_svg_height=&#8221;50&#8243; seperator_shape_background=&#8221;#e2e2e2&#8243; bg_color_value=&#8221;#f7f7f7&#8243; css=&#8221;.vc_custom_1510153051474{padding-top: 20px !important;}&#8221;][vc_column]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-4013\" class=\"aio-icon-box left-icon\" style=\"\"  ><div class=\"aio-icon-left\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:48px;border-style:solid;border-color:#dd3333;border-width:1px;padding:20px;border-radius:500px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"null\" src=\"https:\/\/www.mibhydro.com\/wp-content\/uploads\/2017\/10\/brochure-1.png\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-ibd-block\"><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-4013 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"desktop:27px;\",\"line-height\":\"\"}'  style=\"color:#e10318;\">Data sheet<\/h3><\/div> <!-- header --><\/div> <!-- aio-ibd-block --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[vc_separator color=&#8221;custom&#8221; align=&#8221;align_left&#8221; border_width=&#8221;2&#8243; el_width=&#8221;50&#8243; accent_color=&#8221;#c9c9c9&#8243; css=&#8221;.vc_custom_1510151065777{margin-top: -25px !important;}&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1507797995886{padding-top: 50px !important;}&#8221;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-8603\" class=\"aio-icon-box default-icon\" style=\"\"  ><div class=\"aio-icon-default\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon advanced \"  style=\"color:#ffffff;background:#dd3333;border-style:;border-color:#333333;border-width:1px;width:40px;height:40px;line-height:40px;border-radius:500px;font-size:22px;display:inline-block;\">\n\t<i class=\"Defaults-cogs gears\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-8603 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Characteristics<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-8603 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">\u2022 Kind of press : ARCH Press<br \/>\n\u2022 Force : 8000 kN<br \/>\n\u2022 2 synchronized cylinders<br \/>\n\u2022 Stroke : 800 mm<br \/>\n\u2022 Daylight between tables : 1300 mm<br \/>\n\u2022 Tables : 4400 x 2000 mm<br \/>\n\u2022 Approach speed : 200 mm\/s<br \/>\n\u2022 Variable working speed : from 0 to 5 mm\/s<br \/>\n\u2022 Return speed : 100 mm\/s<br \/>\n\u2022 Total weight : 80 tons<br \/>\n\u2022 Press platens insulation<br \/>\n\u2022 Communication between press\u00a0and loading\/unloading robot<br \/>\n\u2022 Total Power : 50 kW<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column][vc_column width=&#8221;1\/2&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-9218\" class=\"aio-icon-box default-icon\" style=\"\"  ><div class=\"aio-icon-default\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon advanced \"  style=\"color:#ffffff;background:#dd3333;border-style:;border-color:#333333;border-width:1px;width:40px;height:40px;line-height:40px;border-radius:500px;font-size:22px;display:inline-block;\">\n\t<i class=\"Defaults-cloud-download\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-9218 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Download Data sheet<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-9218 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\"><a href=\"http:\/\/www.mibhydro.com\/wp-content\/uploads\/2018\/06\/MIB_FICHE_PRODUIT-6-3.pdf\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1013 size-full\" src=\"http:\/\/www.mibhydro.com\/wp-content\/uploads\/2017\/10\/pdf.png\" alt=\"\" width=\"64\" height=\"64\" \/><\/a><\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; enable_overlay=&#8221;enable_overlay_value&#8221; overlay_color=&#8221;rgba(255,255,255,0.9)&#8221; css=&#8221;.vc_custom_1510152266615{margin-top: 10px !important;}&#8221;][vc_column][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_separator color=&#8221;custom&#8221; align=&#8221;align_left&#8221; border_width=&#8221;2&#8243; accent_color=&#8221;#dd3333&#8243; css=&#8221;.vc_custom_1510152772877{margin-top: 47px !important;}&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]<div class=\"aio-icon-component  vc_custom_1519381786941   style_1\"><div id=\"Info-box-wrap-4897\" class=\"aio-icon-box default-icon\" style=\"\"  ><div class=\"aio-icon-default\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:48px;border-style:solid;border-color:#dd3333;border-width:1px;padding:20px;border-radius:500px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"null\" src=\"https:\/\/www.mibhydro.com\/wp-content\/uploads\/2017\/10\/binoculars.png\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-4897 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"desktop:27px;\",\"line-height\":\"\"}'  style=\"color:#e10318;\">Also see<\/h3><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_separator color=&#8221;custom&#8221; align=&#8221;align_left&#8221; border_width=&#8221;2&#8243; accent_color=&#8221;#dd3333&#8243; css=&#8221;.vc_custom_1510152772877{margin-top: 47px !important;}&#8221;][\/vc_column_inner][\/vc_row_inner]<style type=\"text\/css\" data-type=\"the7_shortcodes-inline-css\">.carousel-shortcode.carousel-shortcode-id-1b025e8bbbb93cb68e1618964e44cd81 .owl-nav a {\n  width: 36px;\n  height: 36px;\n  border-radius: 500px;\n}\n.dt-arrow-border-on.carousel-shortcode.carousel-shortcode-id-1b025e8bbbb93cb68e1618964e44cd81 .owl-nav a:not(:hover):before {\n  border-width: 0px;\n}\n.dt-arrow-hover-border-on.carousel-shortcode.carousel-shortcode-id-1b025e8bbbb93cb68e1618964e44cd81 .owl-nav a:hover:after {\n  border-width: 0px;\n}\n.carousel-shortcode.carousel-shortcode-id-1b025e8bbbb93cb68e1618964e44cd81 .owl-nav a.owl-prev {\n  top: 50%;\n  transform: translateY(calc(-50% + 0px));\n  left: -43px;\n}\n@media all and (-ms-high-contrast: none) {\n  .carousel-shortcode.carousel-shortcode-id-1b025e8bbbb93cb68e1618964e44cd81 .owl-nav a.owl-prev {\n    transform: translateY(-50%);\n    margin-top: 0px;\n  }\n}\n.carousel-shortcode.carousel-shortcode-id-1b025e8bbbb93cb68e1618964e44cd81 .owl-nav a.owl-prev i {\n  padding: 0px 0px 0px 0px;\n}\n.carousel-shortcode.carousel-shortcode-id-1b025e8bbbb93cb68e1618964e44cd81 .owl-nav a.owl-next {\n  top: 50%;\n  transform: translateY(calc(-50% + 0px));\n  right: -43px;\n}\n@media all and (-ms-high-contrast: none) {\n  .carousel-shortcode.carousel-shortcode-id-1b025e8bbbb93cb68e1618964e44cd81 .owl-nav a.owl-next {\n    transform: translateY(-50%);\n    margin-top: 0px;\n  }\n}\n.carousel-shortcode.carousel-shortcode-id-1b025e8bbbb93cb68e1618964e44cd81 .owl-nav a.owl-next i {\n  padding: 0px 0px 0px 0px;\n}\n.carousel-shortcode.carousel-shortcode-id-1b025e8bbbb93cb68e1618964e44cd81 .owl-nav i {\n  font-size: 18px;\n}\n.carousel-shortcode.carousel-shortcode-id-1b025e8bbbb93cb68e1618964e44cd81 .owl-nav a:not(:hover) i,\n.carousel-shortcode.carousel-shortcode-id-1b025e8bbbb93cb68e1618964e44cd81 .owl-nav a:not(:hover) i:before {\n  color: #ffffff;\n  background: none;\n}\n.carousel-shortcode.carousel-shortcode-id-1b025e8bbbb93cb68e1618964e44cd81 .owl-nav a:hover i,\n.carousel-shortcode.carousel-shortcode-id-1b025e8bbbb93cb68e1618964e44cd81 .owl-nav a:hover i:before {\n  color: rgba(255,255,255,0.75);\n  background: none;\n}\n.carousel-shortcode.carousel-shortcode-id-1b025e8bbbb93cb68e1618964e44cd81 .owl-dots {\n  top: calc(100% + 20px);\n  left: 50%;\n  transform: translateX(calc(-50% + 0px));\n}\n@media all and (-ms-high-contrast: none) {\n  .carousel-shortcode.carousel-shortcode-id-1b025e8bbbb93cb68e1618964e44cd81 .owl-dots {\n    transform: translateX(-50%);\n    margin-left: 0px;\n  }\n}\n.carousel-shortcode.carousel-shortcode-id-1b025e8bbbb93cb68e1618964e44cd81 .owl-dot {\n  width: 10px;\n  height: 10px;\n  margin: 0 8px;\n}\n@media screen and (max-width: 778px) {\n  .carousel-shortcode.carousel-shortcode-id-1b025e8bbbb93cb68e1618964e44cd81.hide-arrows .owl-nav a {\n    display: none;\n  }\n}\n@media screen and (max-width: 778px) {\n  .carousel-shortcode.carousel-shortcode-id-1b025e8bbbb93cb68e1618964e44cd81.reposition-arrows .owl-nav .owl-prev {\n    top: 50%;\n    transform: translateY(calc(-50% + 0px));\n    left: 10px;\n  }\n  .carousel-shortcode.carousel-shortcode-id-1b025e8bbbb93cb68e1618964e44cd81.reposition-arrows .owl-nav .owl-next {\n    top: 50%;\n    transform: translateY(calc(-50% + 0px));\n    right: 10px;\n  }\n}\n@media screen and (max-width: 778px) and all and (-ms-high-contrast: none) {\n  .carousel-shortcode.carousel-shortcode-id-1b025e8bbbb93cb68e1618964e44cd81.reposition-arrows .owl-nav .owl-prev {\n    transform: translateY(-50%);\n    margin-top: 0px;\n  }\n}\n@media screen and (max-width: 778px) and all and (-ms-high-contrast: none) {\n  .carousel-shortcode.carousel-shortcode-id-1b025e8bbbb93cb68e1618964e44cd81.reposition-arrows .owl-nav .owl-next {\n    transform: translateY(-50%);\n    margin-top: 0px;\n  }\n}\n<\/style><div class=\"owl-carousel carousel-shortcode dt-owl-carousel-call carousel-shortcode-id-1b025e8bbbb93cb68e1618964e44cd81 bullets-small-dot-stroke reposition-arrows arrows-bg-on dt-arrow-border-on dt-arrow-hover-border-on disable-arrows-hover-bg arrows-hover-bg-on  vc_custom_1515513650238 \" data-scroll-mode=\"1\" data-col-num=\"4\" data-wide-col-num=\"4\" data-laptop-col=\"4\" data-h-tablet-columns-num=\"4\" data-v-tablet-columns-num=\"2\" data-phone-columns-num=\"2\" data-auto-height=\"true\" data-col-gap=\"30\" data-stage-padding=\"0\" data-speed=\"600\" data-autoplay=\"false\" data-autoplay_speed=\"6000\" data-arrows=\"true\" data-bullet=\"false\" data-next-icon=\"icon-ar-017-r\" data-prev-icon=\"icon-ar-017-l\">[vc_row_inner][vc_column_inner][vc_single_image image=&#8221;1566&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;?page_id=1774&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-4845\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-header\" ><a class=\"aio-icon-box-link\" href=\"?page_id=1774\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-4845 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"desktop:15px;\"}'  style=\"\">PRESS FOR R.T.M. PROCESSING<\/h3><\/a><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_single_image image=&#8221;1567&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;?page_id=1775&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-8819\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-header\" ><a class=\"aio-icon-box-link\" href=\"?page_id=1775\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-8819 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"desktop:15px;\"}'  style=\"\">2000T R.T.M COMPRESSION PRESS<\/h3><\/a><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_single_image image=&#8221;1569&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;?page_id=1776&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-4621\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-header\" ><a class=\"aio-icon-box-link\" href=\"?page_id=1776\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-4621 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"desktop:15px;\"}'  style=\"\">S.M.C. COMPRESSION PRESS<\/h3><\/a><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_single_image image=&#8221;1568&#8243; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;?page_id=1777&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-8973\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-header\" ><a class=\"aio-icon-box-link\" href=\"?page_id=1777\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-8973 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"desktop:15px;\"}'  style=\"\">LABORATORY PRESS<\/h3><\/a><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][\/vc_row_inner]<\/div>[\/vc_column][\/vc_row]<\/p>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row&#8221; enable_overlay=&#8221;enable_overlay_value&#8221; overlay_color=&#8221;rgba(255,255,255,0.82)&#8221; seperator_enable=&#8221;seperator_enable_value&#8221; seperator_type=&#8221;tilt_left_seperator&#8221; seperator_svg_height=&#8221;60&#8243; seperator_shape_background=&#8221;#e74c4a&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_separator color=&#8221;custom&#8221; align=&#8221;align_left&#8221; border_width=&#8221;2&#8243; accent_color=&#8221;#c9c9c9&#8243; css=&#8221;.vc_custom_1510151129236{margin-top: -25px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1519381682229{margin-top: 40px !important;}&#8221;]Big SMC composite parts requires presses platens\u00a0which have to be wide and long. Press\u2019 frame\u00a0must be strong enough to avoid any deflection during\u00a0the force uprising to guarantee the straightness\u00a0of the parts. Synchronized cylinders allows\u00a0the perfect parallelism between&hellip;<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":1771,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"class_list":["post-1776","page","type-page","status-publish","hentry","description-off"],"_links":{"self":[{"href":"https:\/\/www.mibhydro.com\/en\/wp-json\/wp\/v2\/pages\/1776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mibhydro.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.mibhydro.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.mibhydro.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mibhydro.com\/en\/wp-json\/wp\/v2\/comments?post=1776"}],"version-history":[{"count":7,"href":"https:\/\/www.mibhydro.com\/en\/wp-json\/wp\/v2\/pages\/1776\/revisions"}],"predecessor-version":[{"id":4825,"href":"https:\/\/www.mibhydro.com\/en\/wp-json\/wp\/v2\/pages\/1776\/revisions\/4825"}],"up":[{"embeddable":true,"href":"https:\/\/www.mibhydro.com\/en\/wp-json\/wp\/v2\/pages\/1771"}],"wp:attachment":[{"href":"https:\/\/www.mibhydro.com\/en\/wp-json\/wp\/v2\/media?parent=1776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}